{"id":410,"date":"2022-05-02T05:23:10","date_gmt":"2022-05-02T05:23:10","guid":{"rendered":"https:\/\/www.pebblecushions.com\/?p=410"},"modified":"2022-05-02T05:23:10","modified_gmt":"2022-05-02T05:23:10","slug":"sledovat-vasu-objednavku","status":"publish","type":"post","link":"https:\/\/www.pebblecushions.com\/sk\/help\/track-your-order\/","title":{"rendered":"Sledovanie va\u0161ej objedn\u00e1vky"},"content":{"rendered":"<p>Kupuj\u00faci dostane ozn\u00e1menie o odoslan\u00ed ihne\u010f po odoslan\u00ed objedn\u00e1vky. Bude mu ozn\u00e1men\u00e9 sledovacie \u010d\u00edslo a sp\u00f4sob sledovania. Postupujte pod\u013ea na\u0161ich pokynov na sledovanie va\u0161ej objedn\u00e1vky.<\/p>","protected":false},"excerpt":{"rendered":"<p>Kupuj\u00faci dostane ozn\u00e1menie o odoslan\u00ed ihne\u010f po odoslan\u00ed objedn\u00e1vky. Bude mu ozn\u00e1men\u00e9 sledovacie \u010d\u00edslo a sp\u00f4sob sledovania. Postupujte pod\u013ea na\u0161ich pokynov na sledovanie va\u0161ej objedn\u00e1vky.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-410","post","type-post","status-publish","format-standard","hentry","category-help"],"_links":{"self":[{"href":"https:\/\/www.pebblecushions.com\/sk\/wp-json\/wp\/v2\/posts\/410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pebblecushions.com\/sk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pebblecushions.com\/sk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pebblecushions.com\/sk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pebblecushions.com\/sk\/wp-json\/wp\/v2\/comments?post=410"}],"version-history":[{"count":1,"href":"https:\/\/www.pebblecushions.com\/sk\/wp-json\/wp\/v2\/posts\/410\/revisions"}],"predecessor-version":[{"id":411,"href":"https:\/\/www.pebblecushions.com\/sk\/wp-json\/wp\/v2\/posts\/410\/revisions\/411"}],"wp:attachment":[{"href":"https:\/\/www.pebblecushions.com\/sk\/wp-json\/wp\/v2\/media?parent=410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pebblecushions.com\/sk\/wp-json\/wp\/v2\/categories?post=410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pebblecushions.com\/sk\/wp-json\/wp\/v2\/tags?post=410"}],"curies":[{"name":"pracovn\u00fd list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}